{"id":22762,"date":"2026-05-30T21:04:18","date_gmt":"2026-05-30T19:04:18","guid":{"rendered":"https:\/\/edicionesdelantal.es\/?post_type=product&#038;p=22762"},"modified":"2026-05-30T21:18:10","modified_gmt":"2026-05-30T19:18:10","slug":"da-windscape-%c2%b7-e-30-donation","status":"publish","type":"product","link":"https:\/\/edicionesdelantal.es\/en\/ticket\/da-windscape-donation-30-e\/","title":{"rendered":"Da WindScape \u00b7 \u20ac 30 Donation"},"content":{"rendered":"<p>Thanks for your donation to the concert DA @ WindScape Brooklyn!<\/p>\n<p>Saturday June 6th 2026 at 6:30 pm<\/p>\n<p>by <strong>D\u00faa da Pel<\/strong> (Eva Guillam\u00f3n and Sonia Meg\u00edas)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Thanks for your donation to the concert DA @ WindScape Brooklyn!<\/p>\n<p>Saturday June 6th 2026 at 6:30 pm<\/p>\n<p>By <a href=\"http:\/\/www.duadapel.org\">D\u00faa da Pel<\/a><\/p>\n","protected":false},"featured_media":22773,"template":"","meta":{"_gspb_post_css":"","pmpro_default_level":"","_uag_custom_page_level_css":""},"product_brand":[],"product_cat":[2047,287],"product_tag":[],"class_list":{"0":"post-22762","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-tickets-en","7":"product_cat-ediciones-delantal-en","8":"pmpro-has-access","10":"first","11":"instock","12":"downloadable","13":"virtual","14":"taxable","15":"purchasable","16":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Da WindScape \u00b7 \u20ac 30 Donation - EdicionesDelantal<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/edicionesdelantal.es\/en\/ticket\/da-windscape-donation-30-e\/\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/edicionesdelantal.es\\\/en\\\/ticket\\\/da-windscape-donation-30-e\\\/\",\"url\":\"https:\\\/\\\/edicionesdelantal.es\\\/en\\\/ticket\\\/da-windscape-donation-30-e\\\/\",\"name\":\"Da WindScape \u00b7 \u20ac 30 Donation - EdicionesDelantal\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/edicionesdelantal.es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/edicionesdelantal.es\\\/en\\\/ticket\\\/da-windscape-donation-30-e\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/edicionesdelantal.es\\\/en\\\/ticket\\\/da-windscape-donation-30-e\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/edicionesdelantal.es\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Da-30-E.png\",\"datePublished\":\"2026-05-30T19:04:18+00:00\",\"dateModified\":\"2026-05-30T19:18:10+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/edicionesdelantal.es\\\/en\\\/ticket\\\/da-windscape-donation-30-e\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/edicionesdelantal.es\\\/en\\\/ticket\\\/da-windscape-donation-30-e\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/edicionesdelantal.es\\\/en\\\/ticket\\\/da-windscape-donation-30-e\\\/#primaryimage\",\"url\":\"https:\\\/\\\/edicionesdelantal.es\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Da-30-E.png\",\"contentUrl\":\"https:\\\/\\\/edicionesdelantal.es\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Da-30-E.png\",\"width\":1470,\"height\":1470},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/edicionesdelantal.es\\\/en\\\/ticket\\\/da-windscape-donation-30-e\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/edicionesdelantal.es\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tienda de Partituras\",\"item\":\"https:\\\/\\\/edicionesdelantal.es\\\/tienda\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Da WindScape \u00b7 \u20ac 30 Donation\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/edicionesdelantal.es\\\/#website\",\"url\":\"https:\\\/\\\/edicionesdelantal.es\\\/\",\"name\":\"EdicionesDelantal\",\"description\":\"Composer Sonia Meg\u00edas&#039; publishing company\",\"publisher\":{\"@id\":\"https:\\\/\\\/edicionesdelantal.es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/edicionesdelantal.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/edicionesdelantal.es\\\/#organization\",\"name\":\"EdicionesDelantal\",\"url\":\"https:\\\/\\\/edicionesdelantal.es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/edicionesdelantal.es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/edicionesdelantal.es\\\/wp-content\\\/uploads\\\/2017\\\/11\\\/a-EdicionesDelantal_LOGOCUADRADO.jpg\",\"contentUrl\":\"https:\\\/\\\/edicionesdelantal.es\\\/wp-content\\\/uploads\\\/2017\\\/11\\\/a-EdicionesDelantal_LOGOCUADRADO.jpg\",\"width\":948,\"height\":948,\"caption\":\"EdicionesDelantal\"},\"image\":{\"@id\":\"https:\\\/\\\/edicionesdelantal.es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Da WindScape \u00b7 \u20ac 30 Donation - EdicionesDelantal","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/edicionesdelantal.es\/en\/ticket\/da-windscape-donation-30-e\/","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/edicionesdelantal.es\/en\/ticket\/da-windscape-donation-30-e\/","url":"https:\/\/edicionesdelantal.es\/en\/ticket\/da-windscape-donation-30-e\/","name":"Da WindScape \u00b7 \u20ac 30 Donation - EdicionesDelantal","isPartOf":{"@id":"https:\/\/edicionesdelantal.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/edicionesdelantal.es\/en\/ticket\/da-windscape-donation-30-e\/#primaryimage"},"image":{"@id":"https:\/\/edicionesdelantal.es\/en\/ticket\/da-windscape-donation-30-e\/#primaryimage"},"thumbnailUrl":"https:\/\/edicionesdelantal.es\/wp-content\/uploads\/2026\/05\/Da-30-E.png","datePublished":"2026-05-30T19:04:18+00:00","dateModified":"2026-05-30T19:18:10+00:00","breadcrumb":{"@id":"https:\/\/edicionesdelantal.es\/en\/ticket\/da-windscape-donation-30-e\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/edicionesdelantal.es\/en\/ticket\/da-windscape-donation-30-e\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/edicionesdelantal.es\/en\/ticket\/da-windscape-donation-30-e\/#primaryimage","url":"https:\/\/edicionesdelantal.es\/wp-content\/uploads\/2026\/05\/Da-30-E.png","contentUrl":"https:\/\/edicionesdelantal.es\/wp-content\/uploads\/2026\/05\/Da-30-E.png","width":1470,"height":1470},{"@type":"BreadcrumbList","@id":"https:\/\/edicionesdelantal.es\/en\/ticket\/da-windscape-donation-30-e\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/edicionesdelantal.es\/en\/"},{"@type":"ListItem","position":2,"name":"Tienda de Partituras","item":"https:\/\/edicionesdelantal.es\/tienda\/"},{"@type":"ListItem","position":3,"name":"Da WindScape \u00b7 \u20ac 30 Donation"}]},{"@type":"WebSite","@id":"https:\/\/edicionesdelantal.es\/#website","url":"https:\/\/edicionesdelantal.es\/","name":"EdicionesDelantal","description":"Composer Sonia Meg\u00edas&#039; publishing company","publisher":{"@id":"https:\/\/edicionesdelantal.es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/edicionesdelantal.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/edicionesdelantal.es\/#organization","name":"EdicionesDelantal","url":"https:\/\/edicionesdelantal.es\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/edicionesdelantal.es\/#\/schema\/logo\/image\/","url":"https:\/\/edicionesdelantal.es\/wp-content\/uploads\/2017\/11\/a-EdicionesDelantal_LOGOCUADRADO.jpg","contentUrl":"https:\/\/edicionesdelantal.es\/wp-content\/uploads\/2017\/11\/a-EdicionesDelantal_LOGOCUADRADO.jpg","width":948,"height":948,"caption":"EdicionesDelantal"},"image":{"@id":"https:\/\/edicionesdelantal.es\/#\/schema\/logo\/image\/"}}]}},"uagb_featured_image_src":{"full":["https:\/\/edicionesdelantal.es\/wp-content\/uploads\/2026\/05\/Da-30-E.png",1470,1470,false],"thumbnail":["https:\/\/edicionesdelantal.es\/wp-content\/uploads\/2026\/05\/Da-30-E-150x150.png",150,150,true],"medium":["https:\/\/edicionesdelantal.es\/wp-content\/uploads\/2026\/05\/Da-30-E-300x300.png",300,300,true],"medium_large":["https:\/\/edicionesdelantal.es\/wp-content\/uploads\/2026\/05\/Da-30-E-768x768.png",768,768,true],"large":["https:\/\/edicionesdelantal.es\/wp-content\/uploads\/2026\/05\/Da-30-E-1024x1024.png",980,980,true],"1536x1536":["https:\/\/edicionesdelantal.es\/wp-content\/uploads\/2026\/05\/Da-30-E.png",1470,1470,false],"2048x2048":["https:\/\/edicionesdelantal.es\/wp-content\/uploads\/2026\/05\/Da-30-E.png",1470,1470,false],"woocommerce_thumbnail":["https:\/\/edicionesdelantal.es\/wp-content\/uploads\/2026\/05\/Da-30-E-324x324.png",324,324,true],"woocommerce_single":["https:\/\/edicionesdelantal.es\/wp-content\/uploads\/2026\/05\/Da-30-E-416x416.png",416,416,true],"woocommerce_gallery_thumbnail":["https:\/\/edicionesdelantal.es\/wp-content\/uploads\/2026\/05\/Da-30-E-100x100.png",100,100,true]},"uagb_author_info":{"display_name":"Sonia Meg\u00edas","author_link":"https:\/\/edicionesdelantal.es\/en\/author\/"},"uagb_comment_info":0,"uagb_excerpt":"Thanks for your donation to the concert DA @ WindScape Brooklyn! Saturday June 6th 2026 at 6:30 pm By D\u00faa da Pel","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/edicionesdelantal.es\/en\/wp-json\/wp\/v2\/product\/22762","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/edicionesdelantal.es\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/edicionesdelantal.es\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/edicionesdelantal.es\/en\/wp-json\/wp\/v2\/media\/22773"}],"wp:attachment":[{"href":"https:\/\/edicionesdelantal.es\/en\/wp-json\/wp\/v2\/media?parent=22762"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/edicionesdelantal.es\/en\/wp-json\/wp\/v2\/product_brand?post=22762"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/edicionesdelantal.es\/en\/wp-json\/wp\/v2\/product_cat?post=22762"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/edicionesdelantal.es\/en\/wp-json\/wp\/v2\/product_tag?post=22762"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}