{"id":23201,"date":"2026-06-05T15:09:39","date_gmt":"2026-06-05T13:09:39","guid":{"rendered":"https:\/\/edicionesdelantal.es\/event\/alicante-la-geometria-de-las-cuerdas-por-el-corodelantal-alicia-narejos\/"},"modified":"2026-06-05T15:16:54","modified_gmt":"2026-06-05T13:16:54","slug":"alicante-la-geometria-de-las-cuerdas-por-el-corodelantal-alicia-narejos","status":"publish","type":"tribe_events","link":"https:\/\/edicionesdelantal.es\/en\/event\/alicante-la-geometria-de-las-cuerdas-por-el-corodelantal-alicia-narejos\/","title":{"rendered":"ALICANTE: &#8220;The Geometry of Strings&#8221; by CoroDelantal + Alicia Narejos"},"content":{"rendered":"<p><iframe loading=\"lazy\" title=\"La geometr\u00eda de las cuerdas\" width=\"980\" height=\"551\" src=\"https:\/\/www.youtube.com\/embed\/MJTAuPLkeRc?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p><iframe loading=\"lazy\" title=\"Coro Delantal 02 23\" width=\"980\" height=\"551\" src=\"https:\/\/www.youtube.com\/embed\/ajwcXYVwi2c?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p>The workshop consists of an encounter between movement, sound and matter. A work of plasticity, which will bring to the scale of human bodies the grids, cradles and other geometries of Eva Lootz&#8217;s string figures. How will the patterns of play, their nature, and the string itself influence the voice and the body? This is the starting point of a research work between the dancer Alicia Narejos, the plastic artist Eva Lootz and Sonia Meg\u00edas, conductor of CoroDelantal. The experiment was born in the MACA in Alicante and will be developed in places like the C\u00edrculo de Bellas Artes in Madrid.<\/p>\n<p>The first show will be on Sunday 12th at 13:00 at Museo de Arte Contempor\u00e1neo de Alicante.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>The workshop consists of an encounter between movement, sound and matter. A work of plasticity, which will bring to the scale of human bodies the grids, cradles and other geometries [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":23198,"template":"","meta":{"_gspb_post_css":"","pmpro_default_level":"","_uag_custom_page_level_css":"","_tribe_events_status":"","_tribe_events_status_reason":"","footnotes":""},"tags":[1839,2426,1840,2704,1382,2508,2082,2136,2225,1821,2705],"tribe_events_cat":[1919],"class_list":["post-23201","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","hentry","tag-alicante-en","tag-alicia-narejos-en","tag-corodelantal-en","tag-cunitas-en","tag-danza","tag-eva-lootz-en","tag-maca-en","tag-museo-en","tag-museo-de-arte-contemporaneo-de-alicante-en","tag-sonia-megias-en","tag-string-figures-en","tribe_events_cat-performance","pmpro-has-access","cat_performance"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ALICANTE: &quot;The Geometry of Strings&quot; by CoroDelantal + Alicia Narejos - EdicionesDelantal<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/edicionesdelantal.es\/en\/event\/alicante-la-geometria-de-las-cuerdas-por-el-corodelantal-alicia-narejos\/\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/edicionesdelantal.es\\\/en\\\/event\\\/alicante-la-geometria-de-las-cuerdas-por-el-corodelantal-alicia-narejos\\\/\",\"url\":\"https:\\\/\\\/edicionesdelantal.es\\\/en\\\/event\\\/alicante-la-geometria-de-las-cuerdas-por-el-corodelantal-alicia-narejos\\\/\",\"name\":\"ALICANTE: \\\"The Geometry of Strings\\\" by CoroDelantal + Alicia Narejos - EdicionesDelantal\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/edicionesdelantal.es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/edicionesdelantal.es\\\/en\\\/event\\\/alicante-la-geometria-de-las-cuerdas-por-el-corodelantal-alicia-narejos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/edicionesdelantal.es\\\/en\\\/event\\\/alicante-la-geometria-de-las-cuerdas-por-el-corodelantal-alicia-narejos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/edicionesdelantal.es\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/Captura-de-Pantalla-2023-02-02-a-las-16.11.57.png\",\"datePublished\":\"2026-06-05T13:09:39+00:00\",\"dateModified\":\"2026-06-05T13:16:54+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/edicionesdelantal.es\\\/en\\\/event\\\/alicante-la-geometria-de-las-cuerdas-por-el-corodelantal-alicia-narejos\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/edicionesdelantal.es\\\/en\\\/event\\\/alicante-la-geometria-de-las-cuerdas-por-el-corodelantal-alicia-narejos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/edicionesdelantal.es\\\/en\\\/event\\\/alicante-la-geometria-de-las-cuerdas-por-el-corodelantal-alicia-narejos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/edicionesdelantal.es\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/Captura-de-Pantalla-2023-02-02-a-las-16.11.57.png\",\"contentUrl\":\"https:\\\/\\\/edicionesdelantal.es\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/Captura-de-Pantalla-2023-02-02-a-las-16.11.57.png\",\"width\":886,\"height\":816},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/edicionesdelantal.es\\\/en\\\/event\\\/alicante-la-geometria-de-las-cuerdas-por-el-corodelantal-alicia-narejos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/edicionesdelantal.es\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Eventos\",\"item\":\"https:\\\/\\\/edicionesdelantal.es\\\/events\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"ALICANTE: \u00abThe Geometry of Strings\u00bb by CoroDelantal + Alicia Narejos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/edicionesdelantal.es\\\/#website\",\"url\":\"https:\\\/\\\/edicionesdelantal.es\\\/\",\"name\":\"EdicionesDelantal\",\"description\":\"Composer Sonia Meg\u00edas&#039; publishing company\",\"publisher\":{\"@id\":\"https:\\\/\\\/edicionesdelantal.es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/edicionesdelantal.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/edicionesdelantal.es\\\/#organization\",\"name\":\"EdicionesDelantal\",\"url\":\"https:\\\/\\\/edicionesdelantal.es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/edicionesdelantal.es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/edicionesdelantal.es\\\/wp-content\\\/uploads\\\/2017\\\/11\\\/a-EdicionesDelantal_LOGOCUADRADO.jpg\",\"contentUrl\":\"https:\\\/\\\/edicionesdelantal.es\\\/wp-content\\\/uploads\\\/2017\\\/11\\\/a-EdicionesDelantal_LOGOCUADRADO.jpg\",\"width\":948,\"height\":948,\"caption\":\"EdicionesDelantal\"},\"image\":{\"@id\":\"https:\\\/\\\/edicionesdelantal.es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ALICANTE: \"The Geometry of Strings\" by CoroDelantal + Alicia Narejos - EdicionesDelantal","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/edicionesdelantal.es\/en\/event\/alicante-la-geometria-de-las-cuerdas-por-el-corodelantal-alicia-narejos\/","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/edicionesdelantal.es\/en\/event\/alicante-la-geometria-de-las-cuerdas-por-el-corodelantal-alicia-narejos\/","url":"https:\/\/edicionesdelantal.es\/en\/event\/alicante-la-geometria-de-las-cuerdas-por-el-corodelantal-alicia-narejos\/","name":"ALICANTE: \"The Geometry of Strings\" by CoroDelantal + Alicia Narejos - EdicionesDelantal","isPartOf":{"@id":"https:\/\/edicionesdelantal.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/edicionesdelantal.es\/en\/event\/alicante-la-geometria-de-las-cuerdas-por-el-corodelantal-alicia-narejos\/#primaryimage"},"image":{"@id":"https:\/\/edicionesdelantal.es\/en\/event\/alicante-la-geometria-de-las-cuerdas-por-el-corodelantal-alicia-narejos\/#primaryimage"},"thumbnailUrl":"https:\/\/edicionesdelantal.es\/wp-content\/uploads\/2026\/06\/Captura-de-Pantalla-2023-02-02-a-las-16.11.57.png","datePublished":"2026-06-05T13:09:39+00:00","dateModified":"2026-06-05T13:16:54+00:00","breadcrumb":{"@id":"https:\/\/edicionesdelantal.es\/en\/event\/alicante-la-geometria-de-las-cuerdas-por-el-corodelantal-alicia-narejos\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/edicionesdelantal.es\/en\/event\/alicante-la-geometria-de-las-cuerdas-por-el-corodelantal-alicia-narejos\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/edicionesdelantal.es\/en\/event\/alicante-la-geometria-de-las-cuerdas-por-el-corodelantal-alicia-narejos\/#primaryimage","url":"https:\/\/edicionesdelantal.es\/wp-content\/uploads\/2026\/06\/Captura-de-Pantalla-2023-02-02-a-las-16.11.57.png","contentUrl":"https:\/\/edicionesdelantal.es\/wp-content\/uploads\/2026\/06\/Captura-de-Pantalla-2023-02-02-a-las-16.11.57.png","width":886,"height":816},{"@type":"BreadcrumbList","@id":"https:\/\/edicionesdelantal.es\/en\/event\/alicante-la-geometria-de-las-cuerdas-por-el-corodelantal-alicia-narejos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/edicionesdelantal.es\/en\/"},{"@type":"ListItem","position":2,"name":"Eventos","item":"https:\/\/edicionesdelantal.es\/events\/"},{"@type":"ListItem","position":3,"name":"ALICANTE: \u00abThe Geometry of Strings\u00bb by CoroDelantal + Alicia Narejos"}]},{"@type":"WebSite","@id":"https:\/\/edicionesdelantal.es\/#website","url":"https:\/\/edicionesdelantal.es\/","name":"EdicionesDelantal","description":"Composer Sonia Meg\u00edas&#039; publishing company","publisher":{"@id":"https:\/\/edicionesdelantal.es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/edicionesdelantal.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/edicionesdelantal.es\/#organization","name":"EdicionesDelantal","url":"https:\/\/edicionesdelantal.es\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/edicionesdelantal.es\/#\/schema\/logo\/image\/","url":"https:\/\/edicionesdelantal.es\/wp-content\/uploads\/2017\/11\/a-EdicionesDelantal_LOGOCUADRADO.jpg","contentUrl":"https:\/\/edicionesdelantal.es\/wp-content\/uploads\/2017\/11\/a-EdicionesDelantal_LOGOCUADRADO.jpg","width":948,"height":948,"caption":"EdicionesDelantal"},"image":{"@id":"https:\/\/edicionesdelantal.es\/#\/schema\/logo\/image\/"}}]}},"uagb_featured_image_src":{"full":["https:\/\/edicionesdelantal.es\/wp-content\/uploads\/2026\/06\/Captura-de-Pantalla-2023-02-02-a-las-16.11.57.png",886,816,false],"thumbnail":["https:\/\/edicionesdelantal.es\/wp-content\/uploads\/2026\/06\/Captura-de-Pantalla-2023-02-02-a-las-16.11.57-150x150.png",150,150,true],"medium":["https:\/\/edicionesdelantal.es\/wp-content\/uploads\/2026\/06\/Captura-de-Pantalla-2023-02-02-a-las-16.11.57-300x276.png",300,276,true],"medium_large":["https:\/\/edicionesdelantal.es\/wp-content\/uploads\/2026\/06\/Captura-de-Pantalla-2023-02-02-a-las-16.11.57-768x707.png",768,707,true],"large":["https:\/\/edicionesdelantal.es\/wp-content\/uploads\/2026\/06\/Captura-de-Pantalla-2023-02-02-a-las-16.11.57.png",886,816,false],"1536x1536":["https:\/\/edicionesdelantal.es\/wp-content\/uploads\/2026\/06\/Captura-de-Pantalla-2023-02-02-a-las-16.11.57.png",886,816,false],"2048x2048":["https:\/\/edicionesdelantal.es\/wp-content\/uploads\/2026\/06\/Captura-de-Pantalla-2023-02-02-a-las-16.11.57.png",886,816,false],"woocommerce_thumbnail":["https:\/\/edicionesdelantal.es\/wp-content\/uploads\/2026\/06\/Captura-de-Pantalla-2023-02-02-a-las-16.11.57-324x324.png",324,324,true],"woocommerce_single":["https:\/\/edicionesdelantal.es\/wp-content\/uploads\/2026\/06\/Captura-de-Pantalla-2023-02-02-a-las-16.11.57-416x383.png",416,383,true],"woocommerce_gallery_thumbnail":["https:\/\/edicionesdelantal.es\/wp-content\/uploads\/2026\/06\/Captura-de-Pantalla-2023-02-02-a-las-16.11.57-100x100.png",100,100,true]},"uagb_author_info":{"display_name":"Sonia Meg\u00edas","author_link":"https:\/\/edicionesdelantal.es\/en\/author\/sonia\/"},"uagb_comment_info":0,"uagb_excerpt":"The workshop consists of an encounter between movement, sound and matter. A work of plasticity, which will bring to the scale of human bodies the grids, cradles and other geometries [&hellip;]","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/edicionesdelantal.es\/en\/wp-json\/wp\/v2\/tribe_events\/23201","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/edicionesdelantal.es\/en\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/edicionesdelantal.es\/en\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/edicionesdelantal.es\/en\/wp-json\/wp\/v2\/users\/2"}],"version-history":[{"count":2,"href":"https:\/\/edicionesdelantal.es\/en\/wp-json\/wp\/v2\/tribe_events\/23201\/revisions"}],"predecessor-version":[{"id":23204,"href":"https:\/\/edicionesdelantal.es\/en\/wp-json\/wp\/v2\/tribe_events\/23201\/revisions\/23204"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/edicionesdelantal.es\/en\/wp-json\/wp\/v2\/media\/23198"}],"wp:attachment":[{"href":"https:\/\/edicionesdelantal.es\/en\/wp-json\/wp\/v2\/media?parent=23201"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/edicionesdelantal.es\/en\/wp-json\/wp\/v2\/tags?post=23201"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/edicionesdelantal.es\/en\/wp-json\/wp\/v2\/tribe_events_cat?post=23201"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}